{"id":6992,"date":"2023-12-18T13:45:02","date_gmt":"2023-12-18T13:45:02","guid":{"rendered":"https:\/\/www.q-bital.com\/?post_type=case-study&#038;p=6992"},"modified":"2023-12-20T08:40:39","modified_gmt":"2023-12-20T08:40:39","slug":"wexford-general-hospital-ireland-2","status":"publish","type":"case-study","link":"https:\/\/www.q-bital.com\/fr_fr\/case-study\/wexford-general-hospital-ireland-2\/","title":{"rendered":"H\u00f4pital g\u00e9n\u00e9ral de Wexford, Irlande"},"content":{"rendered":"<\/p>\n<h3 class=\"wp-block-heading\">Le besoin&nbsp;<\/h3>\n<p>L&#039;h\u00f4pital g\u00e9n\u00e9ral de Wexford a subi d&#039;importants d\u00e9g\u00e2ts lors d&#039;un incendie d\u00e9vastateur, notamment un effondrement partiel du toit ainsi que des d\u00e9g\u00e2ts d&#039;eau et d&#039;incendie sur les b\u00e2timents et les \u00e9quipements m\u00e9dicaux. Les d\u00e9g\u00e2ts se sont \u00e9tendus \u00e0 \u00ab de grandes parties \u00bb de l&#039;h\u00f4pital, ce qui a n\u00e9cessit\u00e9 d&#039;importants travaux de construction et d&#039;\u00e9lectricit\u00e9. Heureusement, personne n&#039;a \u00e9t\u00e9 bless\u00e9 dans l&#039;incendie. Tous les 219 patients pr\u00e9sents sur place, sauf 29, ont d\u00fb \u00eatre \u00e9vacu\u00e9s ou transf\u00e9r\u00e9s vers d&#039;autres \u00e9tablissements et la moiti\u00e9 des lits de l&#039;h\u00f4pital ont \u00e9t\u00e9 ferm\u00e9s. Aux c\u00f4t\u00e9s du service des accidents et des urgences, les proc\u00e9dures d&#039;endoscopie ont \u00e9t\u00e9 l&#039;un des services de l&#039;h\u00f4pital de 270 lits qui ont \u00e9t\u00e9 touch\u00e9s par l&#039;incendie.<\/p>\n<p>Avec une population importante et desservant une communaut\u00e9 de 163 919 personnes, les services de diagnostic de l&#039;h\u00f4pital \u00e9taient d\u00e9j\u00e0 sous pression en termes de demande et de temps d&#039;attente et toute suspension prolong\u00e9e de ces proc\u00e9dures essentielles aurait eu des effets extr\u00eamement n\u00e9gatifs.<\/p>\n<p>L&#039;h\u00f4pital avait besoin d&#039;une solution qui pourrait \u00eatre sur place et op\u00e9rationnelle rapidement et qui pourrait garantir le maintien des niveaux de d\u00e9bit de patients d&#039;avant l&#039;incendie.<\/p>\n<\/p>\n<h3 class=\"wp-block-heading\">Le plan<\/h3>\n<p>En collaboration avec leur partenaire Accuscience Ireland, bas\u00e9 \u00e0 Kildare, et l&#039;\u00e9quipe de l&#039;h\u00f4pital, Q-bital Healthcare Solutions a fait en sorte que Wexford prenne livraison d&#039;une suite d&#039;endoscopie mobile. La suite offrirait une installation \u00ab \u00e0 guichet unique \u00bb depuis la r\u00e9ception, la consultation, la proc\u00e9dure et la r\u00e9cup\u00e9ration, ainsi qu&#039;une installation de d\u00e9contamination interne.<\/p>\n<p>L&#039;installation autonome devait \u00eatre plac\u00e9e dans une zone d\u00e9di\u00e9e sur place, offrant aux patients la possibilit\u00e9 d&#039;assister \u00e0 leurs rendez-vous sans avoir besoin de visiter le b\u00e2timent principal de l&#039;h\u00f4pital.<\/p>\n<p>En attendant son entr\u00e9e en service, l&#039;\u00e9quipe a eu recours \u00e0 des solutions temporaires, comme l&#039;utilisation des blocs op\u00e9ratoires en cas d&#039;urgence, et a prolong\u00e9 les journ\u00e9es et les semaines de travail dans un \u00e9tablissement externe, \u00e9galement g\u00e9r\u00e9 par l&#039;h\u00f4pital. Cependant, ces deux solutions n&#039;\u00e9taient pas viables \u00e0 long terme et entra\u00eenaient des co\u00fbts suppl\u00e9mentaires ainsi que des inconv\u00e9nients en termes de d\u00e9contamination.&nbsp;<\/p>\n<\/p>\n<h3 class=\"wp-block-heading\">La solution<\/h3>\n<p>Suite au soutien minist\u00e9riel, il a \u00e9t\u00e9 convenu que la solution Q-bital r\u00e9pondrait le mieux au besoin urgent de l&#039;h\u00f4pital en mati\u00e8re de r\u00e9tablissement des services d&#039;endoscopie. En attendant sa livraison, l&#039;h\u00f4pital a eu acc\u00e8s \u00e0 des visites virtuelles et \u00e0 d&#039;autres documents fournis par Q-bital pour aider l&#039;\u00e9quipe \u00e0 se familiariser avec l&#039;\u00e9tablissement.<\/p>\n<p>L&#039;installation a \u00e9t\u00e9 livr\u00e9e apr\u00e8s un voyage en voiture et en ferry depuis le site de Manningtree de Q-bital. Apr\u00e8s une p\u00e9riode de travaux sur site comprenant la construction d&#039;un couloir de liaison, la mise en service, les tests et la validation des services publics tels que l&#039;eau et l&#039;\u00e9lectricit\u00e9, l&#039;unit\u00e9 est devenue op\u00e9rationnelle en juin 2023.<\/p>\n<section id=\"section-2-254\" class=\"ct-section\" >\n<div class=\"ct-section-inner-wrap\">\n<div id=\"div_block-12-254\" class=\"ct-div-block\" >\n<div id=\"div_block-8-254\" class=\"ct-div-block\" >\n<div id=\"fancy_icon-5-254\" class=\"ct-fancy-icon\" ><svg id=\"svg-fancy_icon-5-254\"><use xlink:href=\"#FontAwesomeicon-quote-left\"><\/use><\/svg><\/div>\n<\/div>\n<div id=\"div_block-9-254\" class=\"ct-div-block\" >\n<div id=\"text_block-3-254\" class=\"ct-text-block\" >La livraison et l&#039;installation du dispositif se sont d\u00e9roul\u00e9es sans accroc et tr\u00e8s rapidement. Les \u00e9quipes sur place ont \u00e9t\u00e9 tr\u00e8s serviables et Vanguard a form\u00e9 notre personnel. Vanguard joue un r\u00f4le essentiel dans le maintien des services, la gestion des listes d&#039;attente et la prise en charge rapide des patients. Sans lui, tout cela aurait \u00e9t\u00e9 impossible.<\/div>\n<\/div>\n<div id=\"div_block-10-254\" class=\"ct-div-block\" >\n<div id=\"fancy_icon-6-254\" class=\"ct-fancy-icon\" ><svg id=\"svg-fancy_icon-6-254\"><use xlink:href=\"#FontAwesomeicon-quote-right\"><\/use><\/svg><\/div>\n<\/div>\n<\/div>\n<div id=\"div_block-11-254\" class=\"ct-div-block\" >\n<div id=\"text_block-4-254\" class=\"ct-text-block\" >Patricia Hackett, responsable des op\u00e9rations des services cliniques \u00e0 l&#039;h\u00f4pital g\u00e9n\u00e9ral de Wexford<\/div>\n<\/div>\n<\/div>\n<\/section>\n<h3 class=\"wp-block-heading\">Le r\u00e9sultat<\/h3>\n<p>L&#039;installation d&#039;endoscopie mobile Q-bital permet aux cliniciens d&#039;effectuer un nombre \u00e9quivalent de proc\u00e9dures de 18 points JAG par jour. Il fonctionne en moyenne cinq jours par semaine, avec des sessions suppl\u00e9mentaires un samedi sur deux. L&#039;\u00e9quipe effectue une gamme d&#039;interventions, notamment des coloscopies, des gastroscopies et des sigmo\u00efdoscopies.<\/p>\n<p>L&#039;\u00e9quipe de Wexford a salu\u00e9 sa prestation \u00ab transparente \u00bb. Bien qu\u2019il soit plus petit que l\u2019environnement dans lequel l\u2019\u00e9quipe travaillait auparavant, les retours ont \u00e9t\u00e9 positifs de la part du personnel et des patients. Tous deux appr\u00e9cient que l&#039;\u00e9tablissement soit s\u00e9par\u00e9 de l&#039;h\u00f4pital principal, bien que reli\u00e9 par un couloir sp\u00e9cialement construit, en particulier en cas d&#039;\u00e9pid\u00e9mie virale.<\/p>\n<p>En place depuis au moins 12 mois, l&#039;\u00e9tablissement offre la m\u00eame capacit\u00e9 en termes de proc\u00e9dures (18 points JAG plus deux urgences) que l&#039;ancienne salle d&#039;endoscopie interne.<\/p>\n<\/p>\n<h3 class=\"wp-block-heading\">Notre partenariat avec Accuscience<\/h3>\n<p>C&#039;\u00e9tait un projet tr\u00e8s important. Notre partenariat avec&nbsp;<a href=\"https:\/\/www.vanguardhealthcare.co.uk\/partner-programme\/#accuscience\" target=\"_blank\" rel=\"noreferrer noopener\">Accuscience<\/a>&nbsp;nous permettent de concevoir et de fournir rapidement une installation d&#039;endoscopie enti\u00e8rement \u00e9quip\u00e9e.<\/p>\n<section id=\"section-2-254\" class=\"ct-section\" >\n<div class=\"ct-section-inner-wrap\">\n<div id=\"div_block-12-254\" class=\"ct-div-block\" >\n<div id=\"div_block-8-254\" class=\"ct-div-block\" >\n<div id=\"fancy_icon-5-254\" class=\"ct-fancy-icon\" ><svg id=\"svg-fancy_icon-5-254\"><use xlink:href=\"#FontAwesomeicon-quote-left\"><\/use><\/svg><\/div>\n<\/div>\n<div id=\"div_block-9-254\" class=\"ct-div-block\" >\n<div id=\"text_block-3-254\" class=\"ct-text-block\" >\u00ab Les solutions mobiles telles que cette suite d&#039;endoscopie ajoutent rapidement et en toute s\u00e9curit\u00e9 un espace clinique de haute qualit\u00e9 et sont extr\u00eamement utiles lorsque les h\u00f4pitaux doivent prendre des mesures urgentes pour reprendre rapidement leurs services apr\u00e8s une urgence.<\/div>\n<\/div>\n<div id=\"div_block-10-254\" class=\"ct-div-block\" >\n<div id=\"fancy_icon-6-254\" class=\"ct-fancy-icon\" ><svg id=\"svg-fancy_icon-6-254\"><use xlink:href=\"#FontAwesomeicon-quote-right\"><\/use><\/svg><\/div>\n<\/div>\n<\/div>\n<div id=\"div_block-11-254\" class=\"ct-div-block\" >\n<div id=\"text_block-4-254\" class=\"ct-text-block\" >James McCann, directeur g\u00e9n\u00e9ral, Accuscience<\/div>\n<\/div>\n<\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>Suite d&#039;endoscopie mobile \u00e0 l&#039;h\u00f4pital g\u00e9n\u00e9ral de Wexford, Irlande.<\/p>","protected":false},"author":11,"featured_media":7006,"template":"","case-study-category":[],"case-study-topic":[94],"class_list":["post-6992","case-study","type-case-study","status-publish","has-post-thumbnail","hentry","case-study-topic-modular"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wexford General Hospital, Ireland - Q-bital Healthcare Solutions<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.q-bital.com\/fr_fr\/case-study\/wexford-general-hospital-ireland-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wexford General Hospital, Ireland - Q-bital Healthcare Solutions\" \/>\n<meta property=\"og:description\" content=\"Mobile endoscopy suite at Wexford General Hospital, Ireland.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.q-bital.com\/fr_fr\/case-study\/wexford-general-hospital-ireland-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Q-bital Healthcare Solutions\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-20T08:40:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.q-bital.com\/wp-content\/uploads\/sites\/8\/2023\/12\/IMG_20230518_094922-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.q-bital.com\\\/case-study\\\/wexford-general-hospital-ireland-2\\\/\",\"url\":\"https:\\\/\\\/www.q-bital.com\\\/case-study\\\/wexford-general-hospital-ireland-2\\\/\",\"name\":\"Wexford General Hospital, Ireland - Q-bital Healthcare Solutions\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.q-bital.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.q-bital.com\\\/case-study\\\/wexford-general-hospital-ireland-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.q-bital.com\\\/case-study\\\/wexford-general-hospital-ireland-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.q-bital.com\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2023\\\/12\\\/IMG_20230518_094922-scaled.jpg\",\"datePublished\":\"2023-12-18T13:45:02+00:00\",\"dateModified\":\"2023-12-20T08:40:39+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.q-bital.com\\\/case-study\\\/wexford-general-hospital-ireland-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.q-bital.com\\\/case-study\\\/wexford-general-hospital-ireland-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.q-bital.com\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2023\\\/12\\\/IMG_20230518_094922-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.q-bital.com\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2023\\\/12\\\/IMG_20230518_094922-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.q-bital.com\\\/#website\",\"url\":\"https:\\\/\\\/www.q-bital.com\\\/\",\"name\":\"Q-bital Healthcare Solutions\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.q-bital.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"H\u00f4pital g\u00e9n\u00e9ral de Wexford, Irlande - Solutions de soins de sant\u00e9 Q-bital","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.q-bital.com\/fr_fr\/case-study\/wexford-general-hospital-ireland-2\/","og_locale":"fr_FR","og_type":"article","og_title":"Wexford General Hospital, Ireland - Q-bital Healthcare Solutions","og_description":"Mobile endoscopy suite at Wexford General Hospital, Ireland.","og_url":"https:\/\/www.q-bital.com\/fr_fr\/case-study\/wexford-general-hospital-ireland-2\/","og_site_name":"Q-bital Healthcare Solutions","article_modified_time":"2023-12-20T08:40:39+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/www.q-bital.com\/wp-content\/uploads\/sites\/8\/2023\/12\/IMG_20230518_094922-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.q-bital.com\/case-study\/wexford-general-hospital-ireland-2\/","url":"https:\/\/www.q-bital.com\/case-study\/wexford-general-hospital-ireland-2\/","name":"H\u00f4pital g\u00e9n\u00e9ral de Wexford, Irlande - Solutions de soins de sant\u00e9 Q-bital","isPartOf":{"@id":"https:\/\/www.q-bital.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.q-bital.com\/case-study\/wexford-general-hospital-ireland-2\/#primaryimage"},"image":{"@id":"https:\/\/www.q-bital.com\/case-study\/wexford-general-hospital-ireland-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.q-bital.com\/wp-content\/uploads\/sites\/8\/2023\/12\/IMG_20230518_094922-scaled.jpg","datePublished":"2023-12-18T13:45:02+00:00","dateModified":"2023-12-20T08:40:39+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.q-bital.com\/case-study\/wexford-general-hospital-ireland-2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.q-bital.com\/case-study\/wexford-general-hospital-ireland-2\/#primaryimage","url":"https:\/\/www.q-bital.com\/wp-content\/uploads\/sites\/8\/2023\/12\/IMG_20230518_094922-scaled.jpg","contentUrl":"https:\/\/www.q-bital.com\/wp-content\/uploads\/sites\/8\/2023\/12\/IMG_20230518_094922-scaled.jpg","width":2560,"height":1920},{"@type":"WebSite","@id":"https:\/\/www.q-bital.com\/#website","url":"https:\/\/www.q-bital.com\/","name":"Q-bital Healthcare Solutions","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.q-bital.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.q-bital.com\/fr_fr\/wp-json\/wp\/v2\/case-study\/6992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.q-bital.com\/fr_fr\/wp-json\/wp\/v2\/case-study"}],"about":[{"href":"https:\/\/www.q-bital.com\/fr_fr\/wp-json\/wp\/v2\/types\/case-study"}],"author":[{"embeddable":true,"href":"https:\/\/www.q-bital.com\/fr_fr\/wp-json\/wp\/v2\/users\/11"}],"version-history":[{"count":0,"href":"https:\/\/www.q-bital.com\/fr_fr\/wp-json\/wp\/v2\/case-study\/6992\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.q-bital.com\/fr_fr\/wp-json\/wp\/v2\/media\/7006"}],"wp:attachment":[{"href":"https:\/\/www.q-bital.com\/fr_fr\/wp-json\/wp\/v2\/media?parent=6992"}],"wp:term":[{"taxonomy":"case-study-category","embeddable":true,"href":"https:\/\/www.q-bital.com\/fr_fr\/wp-json\/wp\/v2\/case-study-category?post=6992"},{"taxonomy":"case-study-topic","embeddable":true,"href":"https:\/\/www.q-bital.com\/fr_fr\/wp-json\/wp\/v2\/case-study-topic?post=6992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}