{"id":190,"date":"2023-06-13T14:13:50","date_gmt":"2023-06-13T14:13:50","guid":{"rendered":"https:\/\/www.q-bital.com\/?post_type=service&#038;p=190"},"modified":"2023-10-09T11:31:13","modified_gmt":"2023-10-09T11:31:13","slug":"feedback","status":"publish","type":"service","link":"https:\/\/www.q-bital.com\/fr_fr\/service\/feedback\/","title":{"rendered":"Retour"},"content":{"rendered":"<section id=\"section-68-14-text-left-white\" class=\"ct-section\" >\n<div class=\"ct-section-inner-wrap\">\n<div id=\"new_columns-69-14text-left-white\" class=\"ct-new-columns\" >\n<div id=\"div_block-70-14\" class=\"ct-div-block\" >\n<h2 id=\"headline-71-14\" class=\"ct-headline\">Que pensent les patients de nos Espaces Sant\u00e9 ?<\/h2>\n<div id=\"_rich_text-72-14\" class=\"oxy-rich-text\" >\n<p><span id=\"docs-internal-guid-ac2cfb15-7fff-53f2-7807-48e977b0be75\">Il est important pour nous que chaque patient qui subit une intervention dans l&#039;un de nos Espaces de Sant\u00e9 vive une exp\u00e9rience positive. Nous travaillons avec les NHS Trusts et les h\u00f4pitaux pour garantir que nous fournissons le plus haut niveau de service et de soins. Nous appr\u00e9cions tous les commentaires\u00a0; cela nous aide \u00e0 nous am\u00e9liorer continuellement.<\/span><\/p>\n<p dir=\"ltr\"><strong>Voici un aper\u00e7u de certains des commentaires des patients que nous avons re\u00e7us.<\/strong><\/p>\n<blockquote>\n<p dir=\"ltr\"><em>\u00abJe souhaite complimenter et remercier l&#039;\u00e9quipe mobile (unit\u00e9 Vanguard) du service d&#039;endoscopie de l&#039;h\u00f4pital g\u00e9n\u00e9ral de Leicester. aujourd&#039;hui. Mon rendez-vous \u00e9tait \u00e0 13 heures et j&#039;ai \u00e9t\u00e9 vu exactement \u00e0 l&#039;heure. Tout a \u00e9t\u00e9 bien expliqu\u00e9 et le personnel \u00e9tait extr\u00eamement gentil mais \u00e9galement efficace et a rendu cette proc\u00e9dure inconfortable aussi indolore que possible mentalement et physiquement. Tous les niveaux du personnel, depuis la premi\u00e8re infirmi\u00e8re qui m&#039;a admis et qui a rempli les formalit\u00e9s administratives jusqu&#039;\u00e0 l&#039;infirmi\u00e8re Isabella qui me tient la main et me change les id\u00e9es.<\/em><\/p>\n<\/blockquote>\n<blockquote>\n<p dir=\"ltr\"><em>\u00ab Je dois f\u00e9liciter tous les membres du personnel que j&#039;ai rencontr\u00e9s. Ils ont \u00e9t\u00e9 agr\u00e9ables, serviables et m&#039;ont mis \u00e0 l&#039;aise. La proc\u00e9dure a \u00e9t\u00e9 rapide et indolore. L&#039;\u00e9tablissement \u00e9tait propre et accueillant. \u00bb<\/em><\/p>\n<\/blockquote>\n<blockquote>\n<p dir=\"ltr\"><em>\u00ab Tout le personnel \u00e9tait incroyable. John qui a mis ma canule \u00e9tait fabuleux, m&#039;a gard\u00e9 calme et m&#039;a parl\u00e9, ce qui m&#039;a vraiment aid\u00e9. J&#039;\u00e9tais tellement p\u00e9trifi\u00e9e \u00e0 l&#039;id\u00e9e de subir les proc\u00e9dures, mais ce n&#039;\u00e9tait pas aussi grave que je le pensais, et le personnel m&#039;a vraiment aid\u00e9 \u00e0 me calmer et \u00e0 me rassurer.<\/em><\/p>\n<\/blockquote>\n<blockquote>\n<p dir=\"ltr\"><em>&quot;Merci de fournir un environnement sain et des installations propres, indispensables aux soins primaires.&quot;<\/em><\/p>\n<\/blockquote>\n<blockquote>\n<p dir=\"ltr\"><em>\u00ab Tout le personnel est tr\u00e8s courtois et serviable, une proc\u00e9dure pas tr\u00e8s agr\u00e9able rendue beaucoup moins d\u00e9sagr\u00e9able. Une unit\u00e9 tr\u00e8s professionnelle.<\/em><\/p>\n<\/blockquote>\n<blockquote>\n<p dir=\"ltr\"><em>\u201cEnvironnement tr\u00e8s s\u00fbr et confortable, le personnel n&#039;aurait pas pu \u00eatre plus serviable et vous a mis \u00e0 l&#039;aise du d\u00e9but \u00e0 la fin et vous a tout expliqu\u00e9 si bien.\u201d<\/em><\/p>\n<\/blockquote>\n<blockquote>\n<p dir=\"ltr\"><em>&quot;L&#039;ensemble du processus de coloscopie n&#039;est pas agr\u00e9able, mais mon exp\u00e9rience a \u00e9t\u00e9 excellente. Les infirmi\u00e8res amicales et professionnelles et les m\u00e9decins\/techniciens comp\u00e9tents et rassurants ont rendu mon rendez-vous un jeu d&#039;enfant. Merci.&quot;<\/em><\/p>\n<\/blockquote>\n<blockquote>\n<p dir=\"ltr\"><em>&quot;Le personnel a \u00e9t\u00e9 tr\u00e8s professionnel dans son travail et m&#039;a \u00e9galement mis \u00e0 l&#039;aise avant, pendant et apr\u00e8s mon intervention.&quot;<\/em><\/p>\n<\/blockquote>\n<\/div>\n<\/div>\n<div id=\"div_block-74-14\" class=\"ct-div-block\" ><img decoding=\"async\"  id=\"image-75-14\" alt=\"\" src=\"https:\/\/www.q-bital.com\/wp-content\/uploads\/sites\/8\/2023\/06\/What-do-patients-think-of-our-healthcare-spaces-WEB.jpg\" class=\"ct-image\"\/><\/div>\n<\/div>\n<\/div>\n<\/section>\n<section id=\"section-88-34-blue\" class=\"ct-section\" >\n<div class=\"ct-section-inner-wrap\">\n<div id=\"new_columns-89-34-blue\" class=\"ct-new-columns\" >\n<div id=\"div_block-94-34\" class=\"ct-div-block\" ><img decoding=\"async\"  id=\"image-95-34\" alt=\"\" src=\"https:\/\/www.q-bital.com\/wp-content\/uploads\/sites\/8\/2023\/06\/What-do-our-customers-think-of-our-Healthcare-Spaces-WEB.jpg\" class=\"ct-image\"\/><\/div>\n<div id=\"div_block-90-34\" class=\"ct-div-block\" >\n<h2 id=\"headline-91-34\" class=\"ct-headline\">Que pensent nos clients de nos Espaces Sant\u00e9 ? <\/h2>\n<div id=\"_rich_text-92-34\" class=\"oxy-rich-text\" >\n<p>Les commentaires des clients sont extr\u00eamement importants pour nous. Nous sommes tr\u00e8s fiers lorsque nous recevons des commentaires positifs de nos clients, comme les exemples ci-dessous.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Notre personnel et nos animateurs sont hautement comp\u00e9tents<\/strong><\/p>\n<p><em>\u00ab Nous avons b\u00e9n\u00e9fici\u00e9 du soutien d\u2019un membre du personnel clinique tr\u00e8s comp\u00e9tent et exp\u00e9riment\u00e9. Ils avaient des solutions \u00e0 toutes nos questions et l\u2019animateur \u00e9tait excellent.<\/em><\/p>\n<p>Op\u00e9rations, r\u00e9novation du noyau.<\/p>\n<p><em>\u00ab Si vous avez un mauvais conseiller clinique, vous n&#039;obtiendrez pas le meilleur rendement de l&#039;unit\u00e9 et du personnel \u2013 ils doivent aller de pair. Le conseiller clinique que nous avions \u00e9tait un v\u00e9ritable argument de vente pour Vanguard. Cela a rendu l\u2019ensemble du processus beaucoup plus fluide \u00bb.<\/em><\/p>\n<p>Op\u00e9rations, r\u00e9novation du noyau.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Notre r\u00e9putation et notre capacit\u00e9 \u00e0 nous aligner sur les exigences cl\u00e9s des clients<\/strong><\/p>\n<p><em>\u00ab Il y a quelques acteurs avec des blocs op\u00e9ratoires roulants\u2026. il n\u2019y en a pas beaucoup dans l\u2019espace Vanguard qui soient suffisamment flexibles pour pouvoir acc\u00e9der \u00e0 un parking quelque part.<\/em><\/p>\n<p>Consultant, Capacit\u00e9 suppl\u00e9mentaire de base.<\/p>\n<p><em>&quot;Vanguard est compl\u00e8tement diff\u00e9rent de tout ce qui existe sur le march\u00e9, c&#039;est un cin\u00e9ma plug-in pr\u00eat \u00e0 l&#039;emploi.&quot;<\/em><\/p>\n<p>Achats, capacit\u00e9 suppl\u00e9mentaire de base.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>La qualit\u00e9 et l&#039;\u00e9tendue de nos services ont \u00e9t\u00e9 identifi\u00e9es comme des atouts cl\u00e9s par nos clients<\/strong><\/p>\n<p><em>\u00ab Du point de vue de nos organisations avec les th\u00e9\u00e2tres, le niveau \u00e9tait tr\u00e8s bon. L&#039;infrastructure \u00e9tait bonne et les unit\u00e9s \u00e9taient conformes aux normes \u2013 nous n&#039;avons eu aucune plainte.&nbsp;<\/em><\/p>\n<p>Op\u00e9rations, capacit\u00e9 suppl\u00e9mentaire de base.<\/p>\n<p><em>\u00ab Il s&#039;agit d&#039;une solution de haute qualit\u00e9 ; il est charmant, fait ce qui est \u00e9crit sur la bo\u00eete et dispose des installations dont j&#039;ai besoin.<\/em><\/p>\n<p>Op\u00e9rations, remise \u00e0 neuf d&#039;endoscopie.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Les clients appr\u00e9cient notre fiabilit\u00e9 et notre engagement \u00e0 livrer<\/strong><\/p>\n<p><em>\u00abVanguard disposait d&#039;une solide \u00e9quipe de support derri\u00e8re la livraison et la mise en \u0153uvre.\u00bb<\/em><\/p>\n<p>Achats, r\u00e9novation du noyau.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":40,"template":"","meta":{"_acf_changed":false},"case-study-category":[],"case-study-topic":[],"service-type":[96],"class_list":["post-190","service","type-service","status-publish","has-post-thumbnail","hentry","service-type-service"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Feedback - Q-bital Healthcare Solutions<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.q-bital.com\/fr_fr\/service\/feedback\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Feedback - Q-bital Healthcare Solutions\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.q-bital.com\/fr_fr\/service\/feedback\/\" \/>\n<meta property=\"og:site_name\" content=\"Q-bital Healthcare Solutions\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-09T11:31:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.q-bital.com\/wp-content\/uploads\/sites\/8\/2023\/05\/Staffed-operating-theatre1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1045\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.q-bital.com\\\/service\\\/feedback\\\/\",\"url\":\"https:\\\/\\\/www.q-bital.com\\\/service\\\/feedback\\\/\",\"name\":\"Feedback - Q-bital Healthcare Solutions\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.q-bital.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.q-bital.com\\\/service\\\/feedback\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.q-bital.com\\\/service\\\/feedback\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.q-bital.com\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2023\\\/05\\\/Staffed-operating-theatre1.jpg\",\"datePublished\":\"2023-06-13T14:13:50+00:00\",\"dateModified\":\"2023-10-09T11:31:13+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.q-bital.com\\\/service\\\/feedback\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.q-bital.com\\\/service\\\/feedback\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.q-bital.com\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2023\\\/05\\\/Staffed-operating-theatre1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.q-bital.com\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2023\\\/05\\\/Staffed-operating-theatre1.jpg\",\"width\":1500,\"height\":1045},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.q-bital.com\\\/#website\",\"url\":\"https:\\\/\\\/www.q-bital.com\\\/\",\"name\":\"Q-bital Healthcare Solutions\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.q-bital.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Commentaires - Q-bital Healthcare Solutions","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.q-bital.com\/fr_fr\/service\/feedback\/","og_locale":"fr_FR","og_type":"article","og_title":"Feedback - Q-bital Healthcare Solutions","og_url":"https:\/\/www.q-bital.com\/fr_fr\/service\/feedback\/","og_site_name":"Q-bital Healthcare Solutions","article_modified_time":"2023-10-09T11:31:13+00:00","og_image":[{"width":1500,"height":1045,"url":"https:\/\/www.q-bital.com\/wp-content\/uploads\/sites\/8\/2023\/05\/Staffed-operating-theatre1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.q-bital.com\/service\/feedback\/","url":"https:\/\/www.q-bital.com\/service\/feedback\/","name":"Commentaires - Q-bital Healthcare Solutions","isPartOf":{"@id":"https:\/\/www.q-bital.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.q-bital.com\/service\/feedback\/#primaryimage"},"image":{"@id":"https:\/\/www.q-bital.com\/service\/feedback\/#primaryimage"},"thumbnailUrl":"https:\/\/www.q-bital.com\/wp-content\/uploads\/sites\/8\/2023\/05\/Staffed-operating-theatre1.jpg","datePublished":"2023-06-13T14:13:50+00:00","dateModified":"2023-10-09T11:31:13+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.q-bital.com\/service\/feedback\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.q-bital.com\/service\/feedback\/#primaryimage","url":"https:\/\/www.q-bital.com\/wp-content\/uploads\/sites\/8\/2023\/05\/Staffed-operating-theatre1.jpg","contentUrl":"https:\/\/www.q-bital.com\/wp-content\/uploads\/sites\/8\/2023\/05\/Staffed-operating-theatre1.jpg","width":1500,"height":1045},{"@type":"WebSite","@id":"https:\/\/www.q-bital.com\/#website","url":"https:\/\/www.q-bital.com\/","name":"Q-bital Healthcare Solutions","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.q-bital.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.q-bital.com\/fr_fr\/wp-json\/wp\/v2\/service\/190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.q-bital.com\/fr_fr\/wp-json\/wp\/v2\/service"}],"about":[{"href":"https:\/\/www.q-bital.com\/fr_fr\/wp-json\/wp\/v2\/types\/service"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.q-bital.com\/fr_fr\/wp-json\/wp\/v2\/media\/40"}],"wp:attachment":[{"href":"https:\/\/www.q-bital.com\/fr_fr\/wp-json\/wp\/v2\/media?parent=190"}],"wp:term":[{"taxonomy":"case-study-category","embeddable":true,"href":"https:\/\/www.q-bital.com\/fr_fr\/wp-json\/wp\/v2\/case-study-category?post=190"},{"taxonomy":"case-study-topic","embeddable":true,"href":"https:\/\/www.q-bital.com\/fr_fr\/wp-json\/wp\/v2\/case-study-topic?post=190"},{"taxonomy":"service-type","embeddable":true,"href":"https:\/\/www.q-bital.com\/fr_fr\/wp-json\/wp\/v2\/service-type?post=190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}